{"id":3539,"count":1,"description":"","link":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/","name":"Philippines","slug":"philippines","taxonomy":"category","parent":3537,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Philippines Archieven -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Philippines Archieven -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/category\\\/destinations\\\/asia\\\/philippines\\\/\",\"url\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/category\\\/destinations\\\/asia\\\/philippines\\\/\",\"name\":\"Philippines Archieven -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/category\\\/destinations\\\/asia\\\/philippines\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/category\\\/destinations\\\/asia\\\/philippines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destinations\",\"item\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/category\\\/destinations\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Asia\",\"item\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/category\\\/destinations\\\/asia\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Philippines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/\",\"name\":\"\",\"description\":\"Reisblog voor dromers en avonturiers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/youngwildfree.be\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Philippines Archieven -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/","og_locale":"en_US","og_type":"article","og_title":"Philippines Archieven -","og_url":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/","url":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/","name":"Philippines Archieven -","isPartOf":{"@id":"https:\/\/youngwildfree.be\/en\/#website"},"breadcrumb":{"@id":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/philippines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/youngwildfree.be\/en\/"},{"@type":"ListItem","position":2,"name":"Destinations","item":"https:\/\/youngwildfree.be\/en\/category\/destinations\/"},{"@type":"ListItem","position":3,"name":"Asia","item":"https:\/\/youngwildfree.be\/en\/category\/destinations\/asia\/"},{"@type":"ListItem","position":4,"name":"Philippines"}]},{"@type":"WebSite","@id":"https:\/\/youngwildfree.be\/en\/#website","url":"https:\/\/youngwildfree.be\/en\/","name":"","description":"Reisblog voor dromers en avonturiers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/youngwildfree.be\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/youngwildfree.be\/en\/wp-json\/wp\/v2\/categories\/3539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youngwildfree.be\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/youngwildfree.be\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/youngwildfree.be\/en\/wp-json\/wp\/v2\/categories\/3537"}],"wp:post_type":[{"href":"https:\/\/youngwildfree.be\/en\/wp-json\/wp\/v2\/posts?categories=3539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}